{"id":8341,"date":"2017-05-23T12:13:01","date_gmt":"2017-05-23T12:13:01","guid":{"rendered":"http:\/\/fesprosa.org.ar\/portal\/?p=8341"},"modified":"2017-05-23T12:13:01","modified_gmt":"2017-05-23T12:13:01","slug":"inminentes-medidas-gremiales","status":"publish","type":"post","link":"https:\/\/fesprosa.org.ar\/portal\/inminentes-medidas-gremiales\/","title":{"rendered":"INMINENTES MEDIDAS GREMIALES"},"content":{"rendered":"<div class=\"_1dwg _1w_m\">\n<div>\n<div id=\"js_3m2\" class=\"_5pbx userContent\" data-ft=\"{&quot;tn&quot;:&quot;K&quot;}\">\n<div id=\"id_592424b5219945d83256133\" class=\"text_exposed_root text_exposed\">\n<p>INMINENTES MEDIDAS GREMIALES DE 10 MIL TRABAJADORES DE LOS DOS HOSPITALES M\u00c1S GRANDES DEL PA\u00cdS EN RECHAZO AL ACUERDO MACRI \u2013 UPCN, CON EL APOYO DE LOS 30 MIL AFILIADOS DE SU GREMIO NACIONAL FESPROSA<\/p>\n<p>Martes asambleas | Mi\u00e9rcoles conferencia de prensa 8:30 en el Garrahan<\/p>\n<p>La Federaci\u00f3n Sindical de Profesionales de la Salud de la Rep\u00fablica Argentina (FESPROSA), gremio que representa a m\u00e1s de 30 mil m\u00e9dicos, profesionales y trabajadores de la salud p\u00fablica de todo el pa\u00eds, realiza<span class=\"text_exposed_show\">r\u00e1 una conferencia de prensa este mi\u00e9rcoles 24 de mayo a las 8:30 de la ma\u00f1ana en el Hospital Garrahan (Combate de los Pozos 1851) de la Ciudad Aut\u00f3noma de Buenos Aires, en rechazo al acuerdo entre el gremio Uni\u00f3n del Personal Civil de la Naci\u00f3n (UPCN) a trav\u00e9s de su secretario general, Andr\u00e9s Rodr\u00edguez, con el gobierno de Mauricio Macri, \u201cambos responsables de poner de esta manera un techo a las paritarias 2017 de un 20 por ciento y en cuotas, y sin consultar al resto de los gremios estatales afectados, como FESPROSA, la Asociaci\u00f3n de Trabajadores del Estado (ATE) y otros gremios sindicatos que act\u00faan en el \u00e1mbito de la administraci\u00f3n nacional.<\/span><\/p>\n<div class=\"text_exposed_show\">\n<p>En este sentido, el presidente de la FESPROSA expres\u00f3 que \u201cla Asociaci\u00f3n de Profesionales y T\u00e9cnicos del Hospital de Pediatr\u00eda Garrahan y la Asociaci\u00f3n de Profesionales del Hospital Posadas (APHP) del partido bonaerense de Mor\u00f3n que forma parte de la Asociaci\u00f3n Sindical de Profesionales de la Salud de la Provincia de Buenos Aires (CICOP), y a nivel nacional tanto el Posadas como el Garrahan de la FESPROSA, debatir\u00e1n este martes 23 de mayo en asambleas las decisiones gremiales que dar\u00e1n a conocer el mi\u00e9rcoles 24 en la conferencia de prensa, d\u00eda en que tambi\u00e9n realiza una marcha nacional ATE y CICOP una caravana dese el congreso en defensa de la salud p\u00fablica.<\/p>\n<p>\u201cEl acuerdo Macri \u2013 UPCN fue firmado a espaldas de las y los trabajadores, sin asambleas, sin consultas, actitud que adem\u00e1s convalida la estrategia del gobierno de generar la idea de que habr\u00e1 este a\u00f1o una inflaci\u00f3n del 17 por ciento, lo que ser\u00eda una virtual rebaja de sueldos por no actualizar la p\u00e9rdida salarial del 10 por ciento del a\u00f1o pasado y por no atender las proyecciones de este a\u00f1o que no bajan de un 25 por ciento, esto adem\u00e1s acompa\u00f1ado de medidas de flexibilizaci\u00f3n laboral en las condiciones de trabajo impuestas por la administraci\u00f3n de Cambiemos y validado todo por la r\u00fabrica de Andr\u00e9s Rodr\u00edguez\u201d, finaliz\u00f3 Yabkowski.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"_3x-2\"><\/div>\n<div><\/div>\n<\/div>\n<\/div>\n<div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>INMINENTES MEDIDAS GREMIALES DE 10 MIL TRABAJADORES DE LOS DOS HOSPITALES M\u00c1S GRANDES DEL PA\u00cdS EN RECHAZO AL ACUERDO MACRI \u2013 UPCN, CON EL APOYO DE LOS 30 MIL AFILIADOS DE SU GREMIO NACIONAL FESPROSA<\/p>\n","protected":false},"author":4,"featured_media":8017,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,6],"tags":[],"class_list":{"0":"post-8341","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-centro-de-prensa","8":"category-destacados-del-mes"},"_links":{"self":[{"href":"https:\/\/fesprosa.org.ar\/portal\/wp-json\/wp\/v2\/posts\/8341","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fesprosa.org.ar\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fesprosa.org.ar\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fesprosa.org.ar\/portal\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/fesprosa.org.ar\/portal\/wp-json\/wp\/v2\/comments?post=8341"}],"version-history":[{"count":0,"href":"https:\/\/fesprosa.org.ar\/portal\/wp-json\/wp\/v2\/posts\/8341\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fesprosa.org.ar\/portal\/wp-json\/wp\/v2\/media\/8017"}],"wp:attachment":[{"href":"https:\/\/fesprosa.org.ar\/portal\/wp-json\/wp\/v2\/media?parent=8341"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fesprosa.org.ar\/portal\/wp-json\/wp\/v2\/categories?post=8341"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fesprosa.org.ar\/portal\/wp-json\/wp\/v2\/tags?post=8341"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}