{"id":4163,"date":"2014-07-17T12:30:31","date_gmt":"2014-07-17T15:30:31","guid":{"rendered":"http:\/\/www.fesprosa.com.ar\/portal\/?p=4163"},"modified":"2014-07-17T12:30:31","modified_gmt":"2014-07-17T15:30:31","slug":"jornadas-de-reflexion-socio-sanitaria-andres-carrasco","status":"publish","type":"post","link":"https:\/\/fesprosa.org.ar\/portal\/jornadas-de-reflexion-socio-sanitaria-andres-carrasco\/","title":{"rendered":"JORNADAS DE REFLEXI\u00d3N SOCIO SANITARIA ANDR\u00c9S CARRASCO"},"content":{"rendered":"<p>El 15 de agosto pr\u00f3ximo se llevar\u00e1n a cabo las Jornadas Andr\u00e9s Carrasco en la Facultad de Medicina. El encuentro contar\u00e1 con mesas de debate sobre el modelo extractivista y sus resistencias, la producci\u00f3n p\u00fablica de medicamentos, la precariedad laboral, entre otras.<\/p>\n<p>Informes y inscripci\u00f3n: Av. Caseros 4140 CABA | (011) 4921-7716 | fesprosa@fibertel.com.ar<\/p>\n<p style=\"text-align: center;\"><a href=\"http:\/\/fesprosa.org.ar\/portal\/wp-content\/uploads\/2014\/07\/imagen-jornada_redes_socialesV3-031.jpg\"  rel=\"prettyPhoto[pp_gal]\" ><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter  wp-image-4170\" alt=\"imagen-jornada_redes_socialesV3-03\" src=\"http:\/\/fesprosa.org.ar\/portal\/wp-content\/uploads\/2014\/07\/imagen-jornada_redes_socialesV3-031.jpg\" width=\"649\" height=\"1096\" srcset=\"https:\/\/fesprosa.org.ar\/portal\/wp-content\/uploads\/2014\/07\/imagen-jornada_redes_socialesV3-031.jpg 1201w, https:\/\/fesprosa.org.ar\/portal\/wp-content\/uploads\/2014\/07\/imagen-jornada_redes_socialesV3-031-177x300.jpg 177w, https:\/\/fesprosa.org.ar\/portal\/wp-content\/uploads\/2014\/07\/imagen-jornada_redes_socialesV3-031-606x1024.jpg 606w\" sizes=\"auto, (max-width: 649px) 100vw, 649px\" \/><\/a><\/p>\n<h2>Descargar Ficha de Inscripci\u00f3n<\/h2>\n<figure id=\"attachment_945\" class=\"wp-caption aligncenter\" style=\"width: 621px\"><a href=\"http:\/\/fesprosa.org.ar\/portal\/wp-content\/uploads\/2014\/07\/FICHA-INSCRIPCION1.pdf\" target=\"_blank\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-945\" title=\"Descargar Documento\" alt=\"Descargar Documento\" src=\"http:\/\/fesprosa.org.ar\/portal\/wp-content\/uploads\/2014\/03\/descarga1.jpg\" width=\"621\" height=\"166\" \/><\/a><figcaption class=\"wp-caption-text\">Descargar Documento<\/figcaption><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>El 15 de agosto pr\u00f3ximo se llevar\u00e1n a cabo las Jornadas Andr\u00e9s Carrasco en la Facultad de Medicina. El encuentro contar\u00e1 con mesas de debate sobre el modelo extractivista y sus resistencias, la producci\u00f3n p\u00fablica de medicamentos, la precariedad laboral, entre otras. Informes y inscripci\u00f3n: Av. Caseros 4140 CABA | (011) 4921-7716 | fesprosa@fibertel.com.ar Descargar &#8230;<\/p>\n","protected":false},"author":3,"featured_media":4164,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5,10],"tags":[],"class_list":{"0":"post-4163","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-comunicados","8":"category-noticias"},"_links":{"self":[{"href":"https:\/\/fesprosa.org.ar\/portal\/wp-json\/wp\/v2\/posts\/4163","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fesprosa.org.ar\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fesprosa.org.ar\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fesprosa.org.ar\/portal\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/fesprosa.org.ar\/portal\/wp-json\/wp\/v2\/comments?post=4163"}],"version-history":[{"count":0,"href":"https:\/\/fesprosa.org.ar\/portal\/wp-json\/wp\/v2\/posts\/4163\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fesprosa.org.ar\/portal\/wp-json\/wp\/v2\/media\/4164"}],"wp:attachment":[{"href":"https:\/\/fesprosa.org.ar\/portal\/wp-json\/wp\/v2\/media?parent=4163"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fesprosa.org.ar\/portal\/wp-json\/wp\/v2\/categories?post=4163"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fesprosa.org.ar\/portal\/wp-json\/wp\/v2\/tags?post=4163"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}