{"id":15927,"date":"2023-10-25T15:40:50","date_gmt":"2023-10-25T15:40:50","guid":{"rendered":"https:\/\/fesprosa.org.ar\/portal\/?p=15927"},"modified":"2023-10-25T15:40:52","modified_gmt":"2023-10-25T15:40:52","slug":"fesprosa-expreso-su-absoluto-repudio-a-la-condena-del-abogado-alberto-nallar","status":"publish","type":"post","link":"https:\/\/fesprosa.org.ar\/portal\/fesprosa-expreso-su-absoluto-repudio-a-la-condena-del-abogado-alberto-nallar\/","title":{"rendered":"Fesprosa expres\u00f3 su absoluto repudio a la condena del abogado Alberto Nallar"},"content":{"rendered":"\n<p><strong>El doctor Alberto Nallar, primer abogado de los Profesionales Autoconvocados de la Salud (PAUS-Fesprosa), fue condenando a 3 a\u00f1os y 6 meses de prisi\u00f3n por una causa armada. Mar\u00eda Fernanda Boriotti, presidenta de Fesprosa, conden\u00f3 el fallo.<\/strong><\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full is-resized\"><a href=\"https:\/\/fesprosa.org.ar\/portal\/wp-content\/uploads\/2023\/10\/Noticias-25102023.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"300\" src=\"https:\/\/fesprosa.org.ar\/portal\/wp-content\/uploads\/2023\/10\/Noticias-25102023.jpg\" alt=\"\" class=\"wp-image-15928\" style=\"aspect-ratio:1.3333333333333333;width:462px;height:auto\" srcset=\"https:\/\/fesprosa.org.ar\/portal\/wp-content\/uploads\/2023\/10\/Noticias-25102023.jpg 400w, https:\/\/fesprosa.org.ar\/portal\/wp-content\/uploads\/2023\/10\/Noticias-25102023-300x225.jpg 300w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/><\/a><\/figure>\n<\/div>\n\n\n<p>Se le imputa el crimen de \u00abinstigaci\u00f3n a cometer delitos e incitaci\u00f3n a la violencia en concurso real\u00bb, sin ninguna prueba y en complicidad de jueces y fiscales con el gobernador de Jujuy, Gerardo Morales, como forma de criminalizar la protesta social. La condena contempla un embargo de 7 millones de pesos y la inhabilitaci\u00f3n de ejercer su profesi\u00f3n.<\/p>\n\n\n\n<p>Mar\u00eda Fernanda Boriotti, presidenta de la Federaci\u00f3n Sindical de Profesionales de la Salud (Fesprosa), calific\u00f3 al fallo de \u201cvergonzoso\u201d y \u201cabsolutamente orientado a disciplinar a los que luchan por los derechos de los y las trabajadoras y de los pueblos originarios\u201d y exigi\u00f3 la \u201cinmediata revisi\u00f3n y anulaci\u00f3n de esta causa armada\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El doctor Alberto Nallar, primer abogado de los Profesionales Autoconvocados de la Salud (PAUS-Fesprosa), fue condenando a 3 a\u00f1os y 6 meses de prisi\u00f3n por una causa armada. Mar\u00eda Fernanda Boriotti, presidenta de Fesprosa, conden\u00f3 el fallo.<\/p>\n","protected":false},"author":9,"featured_media":15928,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[246,10],"tags":[],"class_list":{"0":"post-15927","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-jujuy","8":"category-noticias"},"_links":{"self":[{"href":"https:\/\/fesprosa.org.ar\/portal\/wp-json\/wp\/v2\/posts\/15927","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fesprosa.org.ar\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fesprosa.org.ar\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fesprosa.org.ar\/portal\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/fesprosa.org.ar\/portal\/wp-json\/wp\/v2\/comments?post=15927"}],"version-history":[{"count":1,"href":"https:\/\/fesprosa.org.ar\/portal\/wp-json\/wp\/v2\/posts\/15927\/revisions"}],"predecessor-version":[{"id":15929,"href":"https:\/\/fesprosa.org.ar\/portal\/wp-json\/wp\/v2\/posts\/15927\/revisions\/15929"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fesprosa.org.ar\/portal\/wp-json\/wp\/v2\/media\/15928"}],"wp:attachment":[{"href":"https:\/\/fesprosa.org.ar\/portal\/wp-json\/wp\/v2\/media?parent=15927"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fesprosa.org.ar\/portal\/wp-json\/wp\/v2\/categories?post=15927"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fesprosa.org.ar\/portal\/wp-json\/wp\/v2\/tags?post=15927"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}