{"id":14786,"date":"2022-08-11T19:07:27","date_gmt":"2022-08-11T19:07:27","guid":{"rendered":"https:\/\/fesprosa.org.ar\/portal\/?p=14786"},"modified":"2022-08-11T19:07:29","modified_gmt":"2022-08-11T19:07:29","slug":"fortalecer-la-autonomia-para-enfrentar-el-ajuste","status":"publish","type":"post","link":"https:\/\/fesprosa.org.ar\/portal\/fortalecer-la-autonomia-para-enfrentar-el-ajuste\/","title":{"rendered":"Fortalecer la Autonom\u00eda para enfrentar el ajuste"},"content":{"rendered":"\n<p><em><strong>El secretario general de Fesprosa, Jorge Yabkowski, es candidato a conducir la Secretar\u00eda de Salud Laboral en la Lista 1 \u201cGerm\u00e1n Abdala\u201d de la CTA Aut\u00f3noma a nivel nacional, y habl\u00f3 de los desaf\u00edos a futuro.<\/strong><\/em><\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-full\"><a href=\"https:\/\/fesprosa.org.ar\/portal\/wp-content\/uploads\/2022\/08\/Noticias-Blog-Prensa-11082022_1.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"708\" height=\"452\" src=\"https:\/\/fesprosa.org.ar\/portal\/wp-content\/uploads\/2022\/08\/Noticias-Blog-Prensa-11082022_1.jpg\" alt=\"\" class=\"wp-image-14787\" srcset=\"https:\/\/fesprosa.org.ar\/portal\/wp-content\/uploads\/2022\/08\/Noticias-Blog-Prensa-11082022_1.jpg 708w, https:\/\/fesprosa.org.ar\/portal\/wp-content\/uploads\/2022\/08\/Noticias-Blog-Prensa-11082022_1-300x192.jpg 300w\" sizes=\"auto, (max-width: 708px) 100vw, 708px\" \/><\/a><\/figure><\/div>\n\n\n\n<p>El secretario general de Fesprosa, Jorge Yabkowski, es candidato a conducir la Secretar\u00eda de Salud Laboral en la Lista 1 \u201cGerm\u00e1n Abdala\u201d de la CTA Aut\u00f3noma a nivel nacional.<\/p>\n\n\n\n<p>Su votaci\u00f3n fue en el Hospital de San\u00a0Isidro d\u00f3nde acompa\u00f1\u00f3 a Judith Villarruel, presidenta de CICOP local y candidata a secretaria de Acci\u00f3n Social de la CTA A Regional San Isidro.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-full\"><a href=\"https:\/\/fesprosa.org.ar\/portal\/wp-content\/uploads\/2022\/08\/Noticias-Blog-Prensa-11082022_2.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"395\" height=\"534\" src=\"https:\/\/fesprosa.org.ar\/portal\/wp-content\/uploads\/2022\/08\/Noticias-Blog-Prensa-11082022_2.jpg\" alt=\"\" class=\"wp-image-14788\" srcset=\"https:\/\/fesprosa.org.ar\/portal\/wp-content\/uploads\/2022\/08\/Noticias-Blog-Prensa-11082022_2.jpg 395w, https:\/\/fesprosa.org.ar\/portal\/wp-content\/uploads\/2022\/08\/Noticias-Blog-Prensa-11082022_2-222x300.jpg 222w\" sizes=\"auto, (max-width: 395px) 100vw, 395px\" \/><\/a><\/figure><\/div>\n\n\n\n<p>En esta entrevista desglosa los principales ejes de trabajo a futuro y la lucha por una salud p\u00fablica de calidad, con salarios y condiciones dignas para sus trabajadores.<\/p>\n\n\n\n<p><strong>\u00bfC\u00f3mo valora estas elecciones de la CTA Aut\u00f3noma?<\/strong><\/p>\n\n\n\n<p>-Para nosotros como Fesprosa, las elecciones de la CTA Aut\u00f3noma son una oportunidad para profundizar el debate sobre los grandes temas que hoy tiene la Argentina. El pa\u00eds est\u00e1 en una crisis de deuda fenomenal, a la cual ha llegado por la aplicaci\u00f3n&nbsp;&nbsp;de los planes de ajuste del Fondo Monetario Internacional, que como es evidente, tras los a\u00f1os de gobierno de Macri y del actual gobierno de Alberto Fern\u00e1ndez, no han resuelto los graves problemas del pa\u00eds, si no que los han empeorado. Es decir que el ajuste sobre el ajuste no trae soluciones.<\/p>\n\n\n\n<p>A pesar de ello, el gobierno insiste, con Guzm\u00e1n, luego Batakis y ahora con Massa, en aplicar&nbsp;&nbsp;recetas recesivas, antiobreras, antijubilados, que la crisis y la deuda las pague el pueblo trabajador. Con lo cual creemos que esta elecci\u00f3n es una oportunidad para reafirmar las banderas hist\u00f3ricas de la CTA Aut\u00f3noma, como la suspensi\u00f3n del pago de la deuda externa, su auditor\u00eda, y por supuesto continuar la militancia en el marco de la Autoconvocatoria.<\/p>\n\n\n\n<p>Tambi\u00e9n es una gran oportunidad para reafirmar lo que es constitutivo y que lleva el nombre nuestra central, que es la autonom\u00eda. La autonom\u00eda no entendida como neutralidad, sino como no subordinaci\u00f3n de la CTA a ning\u00fan proyecto pol\u00edtico partidario, m\u00e1s cuando los dos grandes proyectos pol\u00edticos partidarios, el FDT y JxC, han demostrado, a pesar de la grieta, coincidir en el proyecto hiper extractivista como modelo para nuestro pa\u00eds con sumisi\u00f3n a los organismos financieros internacionales. As\u00ed que la autonom\u00eda es el arma que tiene hoy la CTA para reafirmar la defensa del salario, la defensa de las condiciones de trabajo y reagrupar todas las fuerzas que hoy se oponen al proyecto de Massa a trav\u00e9s de distintas estrategias de unidad de acci\u00f3n y unidad program\u00e1tica.<\/p>\n\n\n\n<p>Es una oportunidad tambi\u00e9n para reafirmar nuestras pol\u00edticas de transversalidad de g\u00e9neros y construir una central verdaderamente feminista.<\/p>\n\n\n\n<p><strong>\u00bfY en el plano de la salud y de las estrategias sanitarias?<\/strong><\/p>\n\n\n\n<p>-La Fesprosa decidi\u00f3 por mayor\u00eda integrar la Lista 1, en el entendimiento de que es en este colectivo donde tambi\u00e9n se van a reafirmar las estrategias de defensa de la salud p\u00fablica, salud universal, paritaria nacional de salud, de lucha contra la precarizaci\u00f3n laboral y el pluriempleo, y donde vamos a continuar criticando las estrategias verticalistas y tecnocr\u00e1ticas que adopt\u00f3 el gobierno en el manejo de la pandemia. Estas se expresan hoy en el plan lanzado por el Ministerio de Salud y el COFESA de priorizar a la salud privada por encima del sistema p\u00fablico.<\/p>\n\n\n\n<p>En funci\u00f3n de eso, creo que la CTA A tiene que jugar un papel fundamental en dar vitalidad al movimiento de los 15 puntos por el Derecho a la Salud, en defensa de la salud universal. Tenemos que seguir bregando por la derogaci\u00f3n de la CUS y su decreto 908\/16 que aun sigue vigente, y abrir un gran debate sobre lo que necesitamos hoy como salud p\u00fablica y lo que necesitan sus trabajadores, que es jerarquizaci\u00f3n laboral y salarial a trav\u00e9s de un instrumento como la Paritaria Nacional de Salud.<\/p>\n\n\n\n<p><strong>Con respecto a su secretar\u00eda, \u00bfqu\u00e9 valoraci\u00f3n hace?<\/strong><\/p>\n\n\n\n<p>-Al hacerme cargo de la Secretar\u00eda de Salud Laboral, en el caso de que la elecci\u00f3n sea favorable a la Lista 1, la idea es retomar las grandes banderas de salud laboral, como la denuncia del r\u00e9gimen regresivo expresado en la ley de ART, la lucha por los derechos de los trabajadores eliminando las horcas caudinas que significan las comisiones m\u00e9dicas y la falta de derechos reparativos que ha tra\u00eddo la reforma del 2014, la batalla por instalar comisiones mixtas en los lugares de trabajo y nombrar delegados de prevenci\u00f3n elegidos democr\u00e1ticamente por los trabajadores para batallar contra los accidentes de trabajo, contra la violencia laboral.Es tambienimprescindible la lucha por la aplicaci\u00f3n a fondo del Convenio 190 y la Resoluci\u00f3n 206 de la OIT sobre violencia laboral. Es decir, un trabajo interdisciplinario de las secretar\u00edas de Salud, con las de G\u00e9nero y Medioambiente, para crear un ambiente de trabajo saludable, con resguardo de los derechos de los trabajadores.<\/p>\n\n\n\n<p><strong>\u00bfC\u00f3mo ve la lucha por la libertad sindical?<\/strong><\/p>\n\n\n\n<p>-La lucha por la libertad sindical tiene que ser un eje fundamental. El Gobierno, a trav\u00e9s de la gesti\u00f3n del ministro Moroni, ha profundizado la defensa del modelo del unicato. El congelamiento de inscripciones y personer\u00edas gremiales para nuevos sindicatos combativos y aut\u00f3nomos es un imperativo en el cual coinciden Moroni, Daer y la CGT.<\/p>\n\n\n\n<p>En ese sentido, estamos muy comprometidos en esta coalici\u00f3n de los gremios privados de la CTA A, encabezada por el SITRAIC, y vamos a participar el 18 de agosto con una jornada nacional de lucha en defensa de los trabajadores de la salud, pero tambi\u00e9n con un eje en la libertad sindical con\u00a0\u00a0marcha al Ministerio de Trabajo para que todo lo que se est\u00e1 denunciando a nivel de la OIT pueda tener repercusi\u00f3n y pueda quebrar este dique de contenci\u00f3n\u00a0\u00a0que significa el sindicalismo empresario junto al Ministerio de Trabajo.<\/p>\n\n\n\n<p class=\"has-small-font-size\">@PrensaFeSProSa<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El secretario general de Fesprosa, Jorge Yabkowski, es candidato a conducir la Secretar\u00eda de Salud Laboral en la Lista 1 \u201cGerm\u00e1n Abdala\u201d de la CTA Aut\u00f3noma a nivel nacional, y habl\u00f3 de los desaf\u00edos a futuro.<\/p>\n","protected":false},"author":9,"featured_media":14787,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10],"tags":[],"class_list":{"0":"post-14786","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-noticias"},"_links":{"self":[{"href":"https:\/\/fesprosa.org.ar\/portal\/wp-json\/wp\/v2\/posts\/14786","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fesprosa.org.ar\/portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fesprosa.org.ar\/portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fesprosa.org.ar\/portal\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/fesprosa.org.ar\/portal\/wp-json\/wp\/v2\/comments?post=14786"}],"version-history":[{"count":0,"href":"https:\/\/fesprosa.org.ar\/portal\/wp-json\/wp\/v2\/posts\/14786\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fesprosa.org.ar\/portal\/wp-json\/wp\/v2\/media\/14787"}],"wp:attachment":[{"href":"https:\/\/fesprosa.org.ar\/portal\/wp-json\/wp\/v2\/media?parent=14786"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fesprosa.org.ar\/portal\/wp-json\/wp\/v2\/categories?post=14786"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fesprosa.org.ar\/portal\/wp-json\/wp\/v2\/tags?post=14786"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}